{"id":4039,"date":"2018-05-13T21:49:03","date_gmt":"2018-05-13T21:49:03","guid":{"rendered":"https:\/\/indesa.com.pa\/?p=4039"},"modified":"2018-11-08T15:01:57","modified_gmt":"2018-11-08T15:01:57","slug":"sector-inmobiliario-residencial","status":"publish","type":"post","link":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/","title":{"rendered":"Sector Inmobiliario Residencial"},"content":{"rendered":"<a href=\"\/wp-content\/uploads\/2018\/08\/Residencial.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-mobile-width=\"0\"  data-scrollbar=\"none\" data-download=\"on\" data-tracking=\"on\" data-newwindow=\"on\" data-pagetextbox=\"off\" data-scrolltotop=\"off\" data-startzoom=\"100\" data-startfpzoom=\"100\" data-toolbar=\"top\" data-toolbar-fixed=\"off\">Residencial<br\/><\/a>\n","protected":false},"excerpt":{"rendered":"Residencial","protected":false},"author":3,"featured_media":3819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[55],"tags":[],"class_list":["post-4039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sector Inmobiliario Residencial - Indesa Panam\u00e1<\/title>\n<meta name=\"description\" content=\"Reportes de Investigaci\u00f3n; Sector Inmobiliario Residencial, desarrollado por Indesa Panam\u00e1\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sector Inmobiliario Residencial - Indesa Panam\u00e1\" \/>\n<meta property=\"og:description\" content=\"Reportes de Investigaci\u00f3n; Sector Inmobiliario Residencial, desarrollado por Indesa Panam\u00e1\" \/>\n<meta property=\"og:url\" content=\"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Indesa Panam\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-13T21:49:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-08T15:01:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/indesa.com.pa\/wp-content\/uploads\/2018\/09\/residencial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"WP Amigo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"WP Amigo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/\"},\"author\":{\"name\":\"WP Amigo\",\"@id\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/#\\\/schema\\\/person\\\/8bbaf3a3d37608679a43155aca416877\"},\"headline\":\"Sector Inmobiliario Residencial\",\"datePublished\":\"2018-05-13T21:49:03+00:00\",\"dateModified\":\"2018-11-08T15:01:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/\"},\"wordCount\":9,\"image\":{\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/indesa.com.pa\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/residencial.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/\",\"url\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/\",\"name\":\"Sector Inmobiliario Residencial - Indesa Panam\u00e1\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/indesa.com.pa\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/residencial.jpg\",\"datePublished\":\"2018-05-13T21:49:03+00:00\",\"dateModified\":\"2018-11-08T15:01:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/#\\\/schema\\\/person\\\/8bbaf3a3d37608679a43155aca416877\"},\"description\":\"Reportes de Investigaci\u00f3n; Sector Inmobiliario Residencial, desarrollado por Indesa Panam\u00e1\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/#primaryimage\",\"url\":\"http:\\\/\\\/indesa.com.pa\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/residencial.jpg\",\"contentUrl\":\"http:\\\/\\\/indesa.com.pa\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/residencial.jpg\",\"width\":370,\"height\":247},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/sector-inmobiliario-residencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sector Inmobiliario Residencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/\",\"name\":\"Indesa Panam\u00e1\",\"description\":\"An\u00e1lisis econ\u00f3mico y finanzas coporativas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/indesa.com.pa\\\/en\\\/#\\\/schema\\\/person\\\/8bbaf3a3d37608679a43155aca416877\",\"name\":\"WP Amigo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/006e9dadd9333e9df112607ef212e068bb7f97bd66296c4c37ed9f2a83d19766?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/006e9dadd9333e9df112607ef212e068bb7f97bd66296c4c37ed9f2a83d19766?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/006e9dadd9333e9df112607ef212e068bb7f97bd66296c4c37ed9f2a83d19766?s=96&d=mm&r=g\",\"caption\":\"WP Amigo\"},\"url\":\"http:\\\/\\\/indesa.com.pa\\\/en\\\/author\\\/wpamigo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sector Inmobiliario Residencial - Indesa Panam\u00e1","description":"Reportes de Investigaci\u00f3n; Sector Inmobiliario Residencial, desarrollado por Indesa Panam\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/","og_locale":"en_US","og_type":"article","og_title":"Sector Inmobiliario Residencial - Indesa Panam\u00e1","og_description":"Reportes de Investigaci\u00f3n; Sector Inmobiliario Residencial, desarrollado por Indesa Panam\u00e1","og_url":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/","og_site_name":"Indesa Panam\u00e1","article_published_time":"2018-05-13T21:49:03+00:00","article_modified_time":"2018-11-08T15:01:57+00:00","og_image":[{"width":370,"height":247,"url":"http:\/\/indesa.com.pa\/wp-content\/uploads\/2018\/09\/residencial.jpg","type":"image\/jpeg"}],"author":"WP Amigo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"WP Amigo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/#article","isPartOf":{"@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/"},"author":{"name":"WP Amigo","@id":"https:\/\/indesa.com.pa\/en\/#\/schema\/person\/8bbaf3a3d37608679a43155aca416877"},"headline":"Sector Inmobiliario Residencial","datePublished":"2018-05-13T21:49:03+00:00","dateModified":"2018-11-08T15:01:57+00:00","mainEntityOfPage":{"@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/"},"wordCount":9,"image":{"@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/#primaryimage"},"thumbnailUrl":"http:\/\/indesa.com.pa\/wp-content\/uploads\/2018\/09\/residencial.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/","url":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/","name":"Sector Inmobiliario Residencial - Indesa Panam\u00e1","isPartOf":{"@id":"https:\/\/indesa.com.pa\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/#primaryimage"},"image":{"@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/#primaryimage"},"thumbnailUrl":"http:\/\/indesa.com.pa\/wp-content\/uploads\/2018\/09\/residencial.jpg","datePublished":"2018-05-13T21:49:03+00:00","dateModified":"2018-11-08T15:01:57+00:00","author":{"@id":"https:\/\/indesa.com.pa\/en\/#\/schema\/person\/8bbaf3a3d37608679a43155aca416877"},"description":"Reportes de Investigaci\u00f3n; Sector Inmobiliario Residencial, desarrollado por Indesa Panam\u00e1","breadcrumb":{"@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/#primaryimage","url":"http:\/\/indesa.com.pa\/wp-content\/uploads\/2018\/09\/residencial.jpg","contentUrl":"http:\/\/indesa.com.pa\/wp-content\/uploads\/2018\/09\/residencial.jpg","width":370,"height":247},{"@type":"BreadcrumbList","@id":"http:\/\/indesa.com.pa\/en\/sector-inmobiliario-residencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/indesa.com.pa\/en\/"},{"@type":"ListItem","position":2,"name":"Sector Inmobiliario Residencial"}]},{"@type":"WebSite","@id":"https:\/\/indesa.com.pa\/en\/#website","url":"https:\/\/indesa.com.pa\/en\/","name":"Indesa Panam\u00e1","description":"An\u00e1lisis econ\u00f3mico y finanzas coporativas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/indesa.com.pa\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/indesa.com.pa\/en\/#\/schema\/person\/8bbaf3a3d37608679a43155aca416877","name":"WP Amigo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/006e9dadd9333e9df112607ef212e068bb7f97bd66296c4c37ed9f2a83d19766?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/006e9dadd9333e9df112607ef212e068bb7f97bd66296c4c37ed9f2a83d19766?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/006e9dadd9333e9df112607ef212e068bb7f97bd66296c4c37ed9f2a83d19766?s=96&d=mm&r=g","caption":"WP Amigo"},"url":"http:\/\/indesa.com.pa\/en\/author\/wpamigo\/"}]}},"_links":{"self":[{"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/posts\/4039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/comments?post=4039"}],"version-history":[{"count":2,"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/posts\/4039\/revisions"}],"predecessor-version":[{"id":4041,"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/posts\/4039\/revisions\/4041"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/media\/3819"}],"wp:attachment":[{"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/media?parent=4039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/categories?post=4039"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/indesa.com.pa\/en\/wp-json\/wp\/v2\/tags?post=4039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}